{"id":17,"count":2,"description":"","link":"https:\/\/www.onecle.com\/blog\/category\/private-equity\/","name":"private equity","slug":"private-equity","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.onecle.com\/blog\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onecle.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.onecle.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.onecle.com\/blog\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}